{"id":1489,"date":"2010-12-20T11:27:22","date_gmt":"2010-12-20T09:27:22","guid":{"rendered":"http:\/\/www.irreel.org\/blog\/?p=1489"},"modified":"2020-05-11T19:20:39","modified_gmt":"2020-05-11T17:20:39","slug":"2003-renard-bleu-esquisses-animalieres","status":"publish","type":"post","link":"https:\/\/www.irreel.ch\/blog\/2003-renard-bleu-esquisses-animalieres\/","title":{"rendered":"2003 Renard Bleu \/ Esquisses animali\u00e8res"},"content":{"rendered":"\n<p>Esquisses animali\u00e8res et jeux de mouvement<\/p>\n\n\n\n<p>Exposition Renard Bleu 2003<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.irreel.ch\/blog\/monotype-aquarelle-animaux-dans-le-marecage\/\"><img loading=\"lazy\" decoding=\"async\" width=\"228\" height=\"300\" src=\"http:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/envol-bleu-marais-1-228x300.jpg\" alt=\"\" class=\"wp-image-5599\" srcset=\"https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/envol-bleu-marais-1-228x300.jpg 228w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/envol-bleu-marais-1-114x150.jpg 114w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/envol-bleu-marais-1.jpg 615w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/a><figcaption>couleurs, formes en eau<\/figcaption><\/figure>\n\n\n\n<p><em>Animaux dans le mar\u00e9cage, monotype \u00e0 l&rsquo;aquarelle<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.irreel.ch\/blog\/monotype-aquarelle\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"216\" src=\"http:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/sable-or-300x216.jpg\" alt=\"\" class=\"wp-image-5601\" srcset=\"https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/sable-or-300x216.jpg 300w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/sable-or-150x108.jpg 150w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/sable-or-768x553.jpg 768w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/sable-or.jpg 807w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>Passages teint\u00e9s<\/figcaption><\/figure>\n\n\n\n<p>Regard dans le sable dor\u00e9, monotype \u00e0 l&rsquo;aquarelle.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.irreel.ch\/blog\/dessin-huile-deux-pourceaux\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"http:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/deux-pourceaux_Fotor-300x201.jpg\" alt=\"\" class=\"wp-image-5615\" srcset=\"https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/deux-pourceaux_Fotor-300x201.jpg 300w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/deux-pourceaux_Fotor-150x101.jpg 150w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/deux-pourceaux_Fotor-768x516.jpg 768w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/deux-pourceaux_Fotor.jpg 953w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>repos, r\u00eaverie<br><\/figcaption><\/figure>\n\n\n\n<p>Deux pourceaux, dessin \u00e0 l&rsquo;huile.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.irreel.ch\/blog\/dessin-dragon-oriental\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"217\" src=\"http:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1-300x217.jpg\" alt=\"\" class=\"wp-image-5590\" srcset=\"https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1-300x217.jpg 300w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1-150x109.jpg 150w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1-768x556.jpg 768w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1-1024x742.jpg 1024w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/dragon-oriental-1.jpg 1030w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>envol d&rsquo;un \u00eatre \u00e9trange<\/figcaption><\/figure>\n\n\n\n<p>Dragon oriental, dessin \u00e0 l&rsquo;aquarelle<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.irreel.ch\/blog\/dessin-lion\/\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"205\" src=\"http:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2-300x205.jpg\" alt=\"\" class=\"wp-image-5587\" srcset=\"https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2-300x205.jpg 300w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2-150x103.jpg 150w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2-768x525.jpg 768w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2-1024x700.jpg 1024w, https:\/\/www.irreel.ch\/blog\/wp-content\/uploads\/lion-2.jpg 1069w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption>M\u00e9ditation<\/figcaption><\/figure>\n\n\n\n<p>Dessin \u00e0 l&rsquo;aquarelle, lion<\/p>\n\n\n\n<p>1)&nbsp;&nbsp; &nbsp;animal des bois, encore non r\u00e9pertori\u00e9&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>2)&nbsp;&nbsp; &nbsp;petit h\u00e9risson, o\u00f9 vas-tu?&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>3)&nbsp;&nbsp; &nbsp;envol de l\u2019oie&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>4)&nbsp;&nbsp; &nbsp;b\u00eate lourde, avan\u00e7ant&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>5)&nbsp;&nbsp; &nbsp;morse se dressant&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>6)&nbsp;&nbsp; &nbsp;petit mammouth orange dans les sables&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>7)&nbsp;&nbsp; &nbsp;raie de couleur vive&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>8)&nbsp;&nbsp; &nbsp;petit animal guignant &nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>9)&nbsp;&nbsp; &nbsp;porc sauvage des bois de Sumatra&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>10)&nbsp;&nbsp; &nbsp;oie en repos, calme de la respiration&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>11)&nbsp;&nbsp; &nbsp;le repos de deux pourceaux velus&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>12)&nbsp;&nbsp; &nbsp;petit dinosaure et un mammif\u00e8re, dialogue amorc\u00e9&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>13)&nbsp;&nbsp; &nbsp;dragon oriental, souple et leste&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>14)&nbsp;&nbsp; &nbsp;lion au repos, m\u00e9ditatif&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>15)&nbsp;&nbsp; &nbsp;\u00e9lan, vent chaud, sable dans les yeux&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>16)&nbsp;&nbsp; &nbsp;pr\u00eat \u00e0 l\u2019envol&nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>17)&nbsp;&nbsp; &nbsp;myst\u00e8re dans les roches sablonneuses&nbsp;&nbsp; &nbsp;pastel, &nbsp;&nbsp; &nbsp;2003<br>18)&nbsp;&nbsp; &nbsp;for\u00eat profonde&nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>19)&nbsp;&nbsp; &nbsp;hibou, regard, petit-\u00eatre \u00e9treinte, jaune-orange&nbsp;&nbsp; &nbsp;monotype aquarelle, &nbsp;&nbsp; &nbsp;2003<br>20)&nbsp;&nbsp; &nbsp;rythmique bleu, orange, jeux tournoyant&nbsp;&nbsp; &nbsp;monotype aquarelle, &nbsp;&nbsp; &nbsp;2003<br>21)&nbsp;&nbsp; &nbsp;lanc\u00e9e du pas, tu touches \u00e0 peine le sol&nbsp;&nbsp; &nbsp;monotype aquarelle, &nbsp;&nbsp; &nbsp;2003<br>22)&nbsp;&nbsp; &nbsp;tendresse, douceur couleur chair, turquoise&nbsp;&nbsp; &nbsp;monotype aquarelle, &nbsp;&nbsp; &nbsp;2003<br>23)&nbsp;&nbsp; &nbsp;pars, vole, vis, toi l\u2019\u00eatre \u00e9nigmatique&nbsp;&nbsp; &nbsp;monotype aquarelle, &nbsp;&nbsp; &nbsp;2003<br>24)&nbsp;&nbsp; &nbsp;grav\u00e9 sur la pierre, dessin\u00e9 sur le sol, bleu, jaune, orange&nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>25)&nbsp;&nbsp; &nbsp;elle saute, elle saute, la musaraigne du d\u00e9sert&nbsp;&nbsp; &nbsp;aquarelle, &nbsp;&nbsp; &nbsp;2003<br>26)&nbsp;&nbsp; &nbsp;jeu des sables&nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>27)&nbsp;&nbsp; &nbsp;bleu vert, eaux, airs, espaces, \u00e0 travers &nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>28)&nbsp;&nbsp; &nbsp;f\u00eate, les places, le lointain, va ton chemin, crois au jour et \u00e0 son \u00e9clat&nbsp;&nbsp; &nbsp;pastel et aquarelle sur papier japonais, &nbsp;&nbsp; &nbsp;2003<br>29)&nbsp;&nbsp; &nbsp;mural, graffiti, vie des couleurs, &nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>30)&nbsp;&nbsp; &nbsp;joie. \u00e9lan, respiration, ouverture, espoir, tu te dis on peut, je peux, l\u2019avenir est une porte ouverte &nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>31)&nbsp;&nbsp; &nbsp;force et joie, animaux sauvages aux couleurs rouges&nbsp;&nbsp; &nbsp;pastel et aquarelle, &nbsp;&nbsp; &nbsp;2003<br>32)&nbsp;&nbsp; &nbsp;il pleut, derri\u00e8re la fen\u00eatre, une lumi\u00e8re, un peu d\u2019activit\u00e9, les jours, &#8230; .&nbsp;&nbsp; &nbsp;pastel et aquarelle sur papier, &nbsp;&nbsp; &nbsp;2003<br>33)&nbsp;&nbsp; &nbsp;petits \u00eatres \u00e9tranges un peu en bois, un peu des marionnettes, fourmillement de vie, croisements, dialogues, chocs&nbsp;&nbsp; &nbsp;chablon, pastel, &nbsp;&nbsp; &nbsp;2003<br>34)&nbsp;&nbsp; &nbsp;falaises, passages vers un au-del\u00e0, \u00e0 franchir pour l\u2019Eldorado, un paradis inconnu, aspiration des explorateurs &nbsp;&nbsp; &nbsp;pastel sur papier, &nbsp;&nbsp; &nbsp;2003<br>35)&nbsp;&nbsp; &nbsp;horizont rouge, lignes bleues, \u00e9nergie&nbsp;&nbsp; &nbsp;pastel sur papier, &nbsp;&nbsp; &nbsp;2003<br>36)&nbsp;&nbsp; &nbsp;colline, barri\u00e8res, teintes claires, passages des couleurs, brise, chaleur,&nbsp;&nbsp; &nbsp;pastel sur papier, &nbsp;&nbsp; &nbsp;2003<br>37)&nbsp;&nbsp; &nbsp;un voyage, le sable, la chaleur, l\u2019\u00e9clat, le soleil, la cit\u00e9 de pierre&nbsp;&nbsp; &nbsp;pastel et aquarelle sur coton, &nbsp;&nbsp; &nbsp;2003<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esquisses animali\u00e8res et jeux de mouvement Exposition Renard Bleu 2003 Animaux dans le mar\u00e9cage, monotype \u00e0 l&rsquo;aquarelle Regard dans le sable dor\u00e9, monotype \u00e0 l&rsquo;aquarelle. Deux pourceaux, dessin \u00e0 l&rsquo;huile. Dragon oriental, dessin \u00e0&#46;&#46;&#46;<\/p>\n","protected":false},"author":191,"featured_media":3912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[168],"tags":[192,552,547],"class_list":["post-1489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exposition","tag-animaux","tag-aquarelle","tag-exposition"],"_links":{"self":[{"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/posts\/1489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/comments?post=1489"}],"version-history":[{"count":13,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/posts\/1489\/revisions"}],"predecessor-version":[{"id":6680,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/posts\/1489\/revisions\/6680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/media\/3912"}],"wp:attachment":[{"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/media?parent=1489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/categories?post=1489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irreel.ch\/blog\/wp-json\/wp\/v2\/tags?post=1489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}